{"id":4687,"date":"2025-04-08T23:44:36","date_gmt":"2025-04-08T23:44:36","guid":{"rendered":"https:\/\/reporte272.com\/portal\/?p=4687"},"modified":"2025-04-08T23:53:56","modified_gmt":"2025-04-08T23:53:56","slug":"una-burla-repentino-interes-del-proyecto-de-paso-superior-ferroviario-de-la-colonia-modelo-en-rio-blanco","status":"publish","type":"post","link":"https:\/\/reporte272.com\/portal\/una-burla-repentino-interes-del-proyecto-de-paso-superior-ferroviario-de-la-colonia-modelo-en-rio-blanco\/","title":{"rendered":"Una burla repentino inter\u00e9s del proyecto de paso superior ferroviario de la Colonia Modelo, en R\u00edo Blanco"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>R\u00edo Blanco, Veracruz. (Reporte272).-<\/strong> Habitantes de la colonia Modelo tachan de una burla y estrategia electoral el repentino inter\u00e9s de las autoridades municipales sobre el proyecto del paso superior ferroviario de la Colonia Modelo, lo anterior tras hacerse viral un oficio de la direcci\u00f3n de obras p\u00fablicas con atenci\u00f3n al presidente Municipal Ricardo P\u00e9rez Garc\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1alan que a menos de 1 mes y 23 d\u00edas de la jornada electoral, les brot\u00f3 el inter\u00e9s por retomar el tan anhelado proyecto de los colonos de la Modelo, misma que fue promesa de campa\u00f1a del ahora alcalde Ricardo P\u00e9rez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El <strong>oficio filtrado en las redes sociales<\/strong> por un participante anonimo que est\u00e1 firmado por el <strong>Ing. Sergio Delfino Salas Zarate Director del Departamento de Obras P\u00fablicas del H. Ayuntamiento de R\u00edo Blanco, Veracruz<\/strong>, a la letra dice: <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Por medio de la presente le mando un cordial saludo y a su vez me permito extenderle la invitaci\u00f3n a la reuni\u00f3n programada el d\u00eda jueves 10 de abril del presente a\u00f1o en un horario de 13:00 hrs para informar a la ciudadan\u00eda de la elaboraci\u00f3n del proyecto llamado &#8220;Paso Superior Ferroviario&#8221; ubicado en la calle Sonora y calle 12 de Octubre en colonia Modelo, Dicha reuni\u00f3n se llevar\u00e1 a cabo en el sal\u00f3n campestre &#8220;los fresnos&#8221; ubicado en calle 16 de septiembre no. 330 entre calle 1 de mayo y 20 de noviembre colonia Modelo del Municipio De Rio Blanco, Ver&#8221;.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los colonos y rioblanquenses ni tarde ni perezosos salieron a denunciar que se trata de una <strong>estrategia electorera <\/strong>y es que se\u00f1alan que llevan m\u00e1s de 30 a\u00f1os con est\u00e1 problem\u00e1tica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00edo Blanco, Veracruz. (Reporte272).- Habitantes de la colonia Modelo tachan de una burla y estrategia electoral el repentino inter\u00e9s de las autoridades municipales sobre el proyecto del paso superior ferroviario de la Colonia Modelo, lo anterior tras hacerse viral un oficio de la direcci\u00f3n de obras p\u00fablicas con atenci\u00f3n al presidente Municipal Ricardo P\u00e9rez Garc\u00eda. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4688,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_2001103103558832_108675811699976":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[5,10],"tags":[],"class_list":["post-4687","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","category-portada"],"_links":{"self":[{"href":"https:\/\/reporte272.com\/portal\/wp-json\/wp\/v2\/posts\/4687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reporte272.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reporte272.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reporte272.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/reporte272.com\/portal\/wp-json\/wp\/v2\/comments?post=4687"}],"version-history":[{"count":3,"href":"https:\/\/reporte272.com\/portal\/wp-json\/wp\/v2\/posts\/4687\/revisions"}],"predecessor-version":[{"id":4692,"href":"https:\/\/reporte272.com\/portal\/wp-json\/wp\/v2\/posts\/4687\/revisions\/4692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reporte272.com\/portal\/wp-json\/wp\/v2\/media\/4688"}],"wp:attachment":[{"href":"https:\/\/reporte272.com\/portal\/wp-json\/wp\/v2\/media?parent=4687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reporte272.com\/portal\/wp-json\/wp\/v2\/categories?post=4687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reporte272.com\/portal\/wp-json\/wp\/v2\/tags?post=4687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}